{"id":10926,"date":"2025-11-19T15:48:12","date_gmt":"2025-11-19T14:48:12","guid":{"rendered":"https:\/\/paffen-sicherheit.de\/?post_type=referenz&#038;p=10926"},"modified":"2025-12-22T04:51:06","modified_gmt":"2025-12-22T03:51:06","slug":"gfo","status":"publish","type":"referenz","link":"https:\/\/paffen-sicherheit.de\/en\/unternehmen\/referenzen\/gfo\/","title":{"rendered":"GFO - Charitable Society of the Franciscan Sisters of Olpe in the Rhineland"},"content":{"rendered":"<p>The GFO is a long-established provider of healthcare facilities, care for the elderly and disabled, educational institutions and numerous social projects. With around 100 facilities in North Rhine-Westphalia and Rhineland-Palatinate, it is one of the largest denominational organisations in Germany and combines Christian values with modern services.<\/p>","protected":false},"author":4,"featured_media":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"thema":[775],"class_list":["post-10926","referenz","type-referenz","status-publish","hentry","thema-objektschutz"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>GFO | Referenz | Paffen Sicherheit<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GFO \u2013 Gemeinn\u00fctzige Gesellschaft der Franziskanerinnen zu Olpe im Rheinland\" \/>\n<meta property=\"og:description\" content=\"Die GFO ist ein traditionsreicher Tr\u00e4ger von Gesundheitseinrichtungen, Senioren- und Behindertenhilfe, Bildungseinrichtungen sowie zahlreichen sozialen Projekten. Mit rund 100 Einrichtungen in Nordrhein-Westfalen und Rheinland-Pfalz z\u00e4hlt sie zu den gr\u00f6\u00dften konfessionellen Tr\u00e4gern in Deutschland und verbindet...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/paffen-sicherheit.de\/en\/company\/references\/gfo\/\" \/>\n<meta property=\"og:site_name\" content=\"Paffen Sicherheit\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/paffen.sicherheit\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-22T03:51:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@InfoPaffen\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/paffen-sicherheit.de\\\/en\\\/wp-json\\\/wp\\\/v2\\\/referenz\\\/10926\",\"url\":\"https:\\\/\\\/paffen-sicherheit.de\\\/en\\\/wp-json\\\/wp\\\/v2\\\/referenz\\\/10926\",\"name\":\"GFO | Referenz | Paffen Sicherheit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paffen-sicherheit.de\\\/en\\\/#website\"},\"datePublished\":\"2025-11-19T14:48:12+00:00\",\"dateModified\":\"2025-12-22T03:51:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/paffen-sicherheit.de\\\/en\\\/wp-json\\\/wp\\\/v2\\\/referenz\\\/10926\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/paffen-sicherheit.de\\\/en\\\/wp-json\\\/wp\\\/v2\\\/referenz\\\/10926\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/paffen-sicherheit.de\\\/en\\\/wp-json\\\/wp\\\/v2\\\/referenz\\\/10926\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/paffen-sicherheit.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GFO \u2013 Gemeinn\u00fctzige Gesellschaft der Franziskanerinnen zu Olpe im Rheinland\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/paffen-sicherheit.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/paffen-sicherheit.de\\\/en\\\/\",\"name\":\"Paffen Sicherheit\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/paffen-sicherheit.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/paffen-sicherheit.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/paffen-sicherheit.de\\\/en\\\/#organization\",\"name\":\"Paffen Wach- und Sicherheitsdienst GmbH\",\"alternateName\":\"Paffen Sicherheitsdienst\",\"url\":\"https:\\\/\\\/paffen-sicherheit.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/paffen-sicherheit.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/paffen-sicherheit.de\\\/wp-content\\\/uploads\\\/cropped-paffenfavicon2.0.png\",\"contentUrl\":\"https:\\\/\\\/paffen-sicherheit.de\\\/wp-content\\\/uploads\\\/cropped-paffenfavicon2.0.png\",\"width\":512,\"height\":512,\"caption\":\"Paffen Wach- und Sicherheitsdienst GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/paffen-sicherheit.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/paffen.sicherheit\\\/\",\"https:\\\/\\\/x.com\\\/InfoPaffen\",\"https:\\\/\\\/www.instagram.com\\\/paffensicherheit\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/paffen-wach-und-sicherheitsdienst-gmbh\\\/\"],\"description\":\"Lokal ans\u00e4ssiger Sicherheitsdienst f\u00fcr den Gro\u00dfraum NRW mit Standorten in Bonn, K\u00f6ln, D\u00fcsseldorf, Duisburg, Koblenz und Essen. Als mittelst\u00e4ndische, zertifizierte Sicherheitsfirma ist Paffen Wachdienst & Sicherheitsdienst f\u00fcr Gesch\u00e4fts- wie Privatkunden der erste Ansprechpartner f\u00fcr alle sicherheitsrelevanten Themen im Bereich Objektschutz, Werkschutz, Personenschutz, sowie Veranstaltungsschutz. Ladendetektiv und Sicherungsposten.\",\"email\":\"info@paffen-sicherheit.de\",\"telephone\":\"0228 97 27 55 36\",\"legalName\":\"Paffen Wach- und Sicherheitsdienst GmbH\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"GFO | Reference | Paffen Safety","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_GB","og_type":"article","og_title":"GFO \u2013 Gemeinn\u00fctzige Gesellschaft der Franziskanerinnen zu Olpe im Rheinland","og_description":"Die GFO ist ein traditionsreicher Tr\u00e4ger von Gesundheitseinrichtungen, Senioren- und Behindertenhilfe, Bildungseinrichtungen sowie zahlreichen sozialen Projekten. Mit rund 100 Einrichtungen in Nordrhein-Westfalen und Rheinland-Pfalz z\u00e4hlt sie zu den gr\u00f6\u00dften konfessionellen Tr\u00e4gern in Deutschland und verbindet...","og_url":"https:\/\/paffen-sicherheit.de\/en\/company\/references\/gfo\/","og_site_name":"Paffen Sicherheit","article_publisher":"https:\/\/www.facebook.com\/paffen.sicherheit\/","article_modified_time":"2025-12-22T03:51:06+00:00","twitter_card":"summary_large_image","twitter_site":"@InfoPaffen","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/paffen-sicherheit.de\/en\/wp-json\/wp\/v2\/referenz\/10926","url":"https:\/\/paffen-sicherheit.de\/en\/wp-json\/wp\/v2\/referenz\/10926","name":"GFO | Reference | Paffen Safety","isPartOf":{"@id":"https:\/\/paffen-sicherheit.de\/en\/#website"},"datePublished":"2025-11-19T14:48:12+00:00","dateModified":"2025-12-22T03:51:06+00:00","breadcrumb":{"@id":"https:\/\/paffen-sicherheit.de\/en\/wp-json\/wp\/v2\/referenz\/10926\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/paffen-sicherheit.de\/en\/wp-json\/wp\/v2\/referenz\/10926"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/paffen-sicherheit.de\/en\/wp-json\/wp\/v2\/referenz\/10926\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/paffen-sicherheit.de\/en\/"},{"@type":"ListItem","position":2,"name":"GFO \u2013 Gemeinn\u00fctzige Gesellschaft der Franziskanerinnen zu Olpe im Rheinland"}]},{"@type":"WebSite","@id":"https:\/\/paffen-sicherheit.de\/en\/#website","url":"https:\/\/paffen-sicherheit.de\/en\/","name":"Paffen Security","description":"","publisher":{"@id":"https:\/\/paffen-sicherheit.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/paffen-sicherheit.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/paffen-sicherheit.de\/en\/#organization","name":"Paffen Security Services GmbH","alternateName":"Paffen Sicherheitsdienst","url":"https:\/\/paffen-sicherheit.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/paffen-sicherheit.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/paffen-sicherheit.de\/wp-content\/uploads\/cropped-paffenfavicon2.0.png","contentUrl":"https:\/\/paffen-sicherheit.de\/wp-content\/uploads\/cropped-paffenfavicon2.0.png","width":512,"height":512,"caption":"Paffen Wach- und Sicherheitsdienst GmbH"},"image":{"@id":"https:\/\/paffen-sicherheit.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/paffen.sicherheit\/","https:\/\/x.com\/InfoPaffen","https:\/\/www.instagram.com\/paffensicherheit\/","https:\/\/www.linkedin.com\/company\/paffen-wach-und-sicherheitsdienst-gmbh\/"],"description":"Local security service for the wider NRW region with locations in Bonn, Cologne, D\u00fcsseldorf, Duisburg, Koblenz, and Essen. As a medium-sized, certified security company, Paffen Wachdienst &amp; Sicherheitsdienst is the first point of contact for both business and private clients for all security-related matters in the areas of property protection, industrial security, personal protection, and event security. Store detective and safety guard.","email":"info@paffen-sicherheit.de","telephone":"0228 97 27 55 36","legalName":"Paffen Wach- und Sicherheitsdienst GmbH"}]}},"_links":{"self":[{"href":"https:\/\/paffen-sicherheit.de\/en\/wp-json\/wp\/v2\/referenz\/10926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paffen-sicherheit.de\/en\/wp-json\/wp\/v2\/referenz"}],"about":[{"href":"https:\/\/paffen-sicherheit.de\/en\/wp-json\/wp\/v2\/types\/referenz"}],"author":[{"embeddable":true,"href":"https:\/\/paffen-sicherheit.de\/en\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":7,"href":"https:\/\/paffen-sicherheit.de\/en\/wp-json\/wp\/v2\/referenz\/10926\/revisions"}],"predecessor-version":[{"id":11222,"href":"https:\/\/paffen-sicherheit.de\/en\/wp-json\/wp\/v2\/referenz\/10926\/revisions\/11222"}],"wp:attachment":[{"href":"https:\/\/paffen-sicherheit.de\/en\/wp-json\/wp\/v2\/media?parent=10926"}],"wp:term":[{"taxonomy":"thema","embeddable":true,"href":"https:\/\/paffen-sicherheit.de\/en\/wp-json\/wp\/v2\/thema?post=10926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}